{"id":9932,"date":"2026-02-27T10:35:20","date_gmt":"2026-02-27T09:35:20","guid":{"rendered":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol.png"},"modified":"2026-02-27T10:35:20","modified_gmt":"2026-02-27T09:35:20","slug":"disseny-sense-titol","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/ceipmdangels\/670-2\/attachment\/disseny-sense-titol\/","title":{"rendered":"Disseny sense t\u00edtol"},"author":1,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-9932","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"75\" src=\"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-300x75.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-300x75.png 300w, https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-1024x256.png 1024w, https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-768x192.png 768w, https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-1536x384.png 1536w, https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol.png 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol.png'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1920,"height":480,"file":"2026\/02\/Disseny-sense-titol.png","filesize":128878,"sizes":{"medium":{"file":"Disseny-sense-titol-300x75.png","width":300,"height":75,"filesize":19786,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-300x75.png"},"large":{"file":"Disseny-sense-titol-1024x256.png","width":1024,"height":256,"filesize":94457,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-1024x256.png"},"thumbnail":{"file":"Disseny-sense-titol-150x150.png","width":150,"height":150,"filesize":4629,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-150x150.png"},"medium_large":{"file":"Disseny-sense-titol-768x192.png","width":768,"height":192,"filesize":67749,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-768x192.png"},"1536x1536":{"file":"Disseny-sense-titol-1536x384.png","width":1536,"height":384,"filesize":144956,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-1536x384.png"},"thumb-300":{"file":"Disseny-sense-titol-300x250.png","width":300,"height":250,"filesize":22617,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-300x250.png"},"thumb-200":{"file":"Disseny-sense-titol-200x150.png","width":200,"height":150,"filesize":14749,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol-200x150.png"},"full":{"file":"Disseny-sense-titol.png","width":1920,"height":480,"mime_type":"image\/png","source_url":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":670,"source_url":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-content\/uploads\/usu320\/2026\/02\/Disseny-sense-titol.png","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-json\/wp\/v2\/media\/9932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceipmdangels\/wp-json\/wp\/v2\/comments?post=9932"}]}}