{"id":9636,"date":"2023-06-03T13:24:26","date_gmt":"2023-06-03T11:24:26","guid":{"rendered":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13.jpeg"},"modified":"2023-06-03T13:26:28","modified_gmt":"2023-06-03T11:26:28","slug":"2juny13","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/ceipflix\/general\/dia-mundial-del-medi-ambient-i-de-la-bicicleta\/attachment\/2juny13\/","title":{"rendered":"2juny13"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"class_list":["post-9636","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13-300x225.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13-300x225.jpeg 300w, https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13-768x576.jpeg 768w, https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13-200x150.jpeg 200w, https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13.jpeg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Observatori de la llacuna<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":768,"file":"2023\/06\/2juny13.jpeg","sizes":{"medium":{"file":"2juny13-300x225.jpeg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13-300x225.jpeg"},"thumbnail":{"file":"2juny13-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13-150x150.jpeg"},"medium_large":{"file":"2juny13-768x576.jpeg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13-768x576.jpeg"},"thumb-300":{"file":"2juny13-300x250.jpeg","width":300,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13-300x250.jpeg"},"thumb-200":{"file":"2juny13-200x150.jpeg","width":200,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13-200x150.jpeg"},"full":{"file":"2juny13.jpeg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":9632,"source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/06\/2juny13.jpeg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceipflix\/wp-json\/wp\/v2\/media\/9636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceipflix\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceipflix\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceipflix\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceipflix\/wp-json\/wp\/v2\/comments?post=9636"}]}}