{"id":10041,"date":"2023-11-03T17:48:05","date_gmt":"2023-11-03T16:48:05","guid":{"rendered":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1.jpeg"},"modified":"2023-11-03T17:48:05","modified_gmt":"2023-11-03T16:48:05","slug":"whatsapp-image-2023-11-03-at-17-12-07-1","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/ceipflix\/general\/primera-trobada-de-padrins-lectors-entre-i4-i-3r\/attachment\/whatsapp-image-2023-11-03-at-17-12-07-1\/","title":{"rendered":"WhatsApp Image 2023-11-03 at 17.12.07 (1)"},"author":42,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"class_list":["post-10041","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"135\" src=\"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-300x135.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-300x135.jpeg 300w, https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-1024x461.jpeg 1024w, https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-768x346.jpeg 768w, https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-1536x691.jpeg 1536w, https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":720,"file":"2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1.jpeg","sizes":{"medium":{"file":"WhatsApp-Image-2023-11-03-at-17.12.07-1-300x135.jpeg","width":300,"height":135,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-300x135.jpeg"},"large":{"file":"WhatsApp-Image-2023-11-03-at-17.12.07-1-1024x461.jpeg","width":1024,"height":461,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-1024x461.jpeg"},"thumbnail":{"file":"WhatsApp-Image-2023-11-03-at-17.12.07-1-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-150x150.jpeg"},"medium_large":{"file":"WhatsApp-Image-2023-11-03-at-17.12.07-1-768x346.jpeg","width":768,"height":346,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-768x346.jpeg"},"1536x1536":{"file":"WhatsApp-Image-2023-11-03-at-17.12.07-1-1536x691.jpeg","width":1536,"height":691,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-1536x691.jpeg"},"thumb-300":{"file":"WhatsApp-Image-2023-11-03-at-17.12.07-1-300x250.jpeg","width":300,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-300x250.jpeg"},"thumb-200":{"file":"WhatsApp-Image-2023-11-03-at-17.12.07-1-200x150.jpeg","width":200,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1-200x150.jpeg"},"full":{"file":"WhatsApp-Image-2023-11-03-at-17.12.07-1.jpeg","width":1600,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":9951,"source_url":"https:\/\/agora.xtec.cat\/ceipflix\/wp-content\/uploads\/usu61\/2023\/10\/WhatsApp-Image-2023-11-03-at-17.12.07-1.jpeg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceipflix\/wp-json\/wp\/v2\/media\/10041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceipflix\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceipflix\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceipflix\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceipflix\/wp-json\/wp\/v2\/comments?post=10041"}]}}