{"id":10,"count":48,"description":"","link":"https:\/\/agora.xtec.cat\/ceipcal-lipolis\/categoria\/primaria\/1r\/","name":"1r","slug":"1r","taxonomy":"category","parent":5,"meta":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceipcal-lipolis\/wp-json\/wp\/v2\/categories\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceipcal-lipolis\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceipcal-lipolis\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceipcal-lipolis\/wp-json\/wp\/v2\/categories\/5"}],"wp:post_type":[{"href":"https:\/\/agora.xtec.cat\/ceipcal-lipolis\/wp-json\/wp\/v2\/posts?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}