{"id":2335,"date":"2020-05-06T12:32:09","date_gmt":"2020-05-06T10:32:09","guid":{"rendered":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743.jpg"},"modified":"2020-05-06T12:32:09","modified_gmt":"2020-05-06T10:32:09","slug":"20200506_100743","status":"inherit","type":"attachment","link":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/20200506_100743\/","title":{"rendered":"20200506_100743"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0},"class_list":["post-2335","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743-300x300.jpg 300w, https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743-150x150.jpg 150w, https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743-768x768.jpg 768w, https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743-1024x1024.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p><a href='https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743.jpg'><\/a><\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2896,"height":2896,"file":"2020\/05\/20200506_100743.jpg","sizes":{"thumbnail":{"file":"20200506_100743-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743-150x150.jpg"},"medium":{"file":"20200506_100743-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743-300x300.jpg"},"medium_large":{"file":"20200506_100743-768x768.jpg","width":768,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743-768x768.jpg"},"large":{"file":"20200506_100743-1024x1024.jpg","width":1024,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743-1024x1024.jpg"},"thumb-300":{"file":"20200506_100743-300x250.jpg","width":300,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743-300x250.jpg"},"thumb-200":{"file":"20200506_100743-200x150.jpg","width":200,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743-200x150.jpg"},"full":{"file":"20200506_100743.jpg","width":2896,"height":2896,"mime_type":"image\/jpeg","source_url":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-content\/uploads\/usu1068\/2020\/05\/20200506_100743.jpg","_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-json\/wp\/v2\/media\/2335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-torrescasana-espoia\/wp-json\/wp\/v2\/comments?post=2335"}]}}