{"id":2913,"date":"2019-05-08T15:59:34","date_gmt":"2019-05-08T13:59:34","guid":{"rendered":"http:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/?p=2913"},"modified":"2019-05-08T16:00:10","modified_gmt":"2019-05-08T14:00:10","slug":"experiment-amb-pinyes-les-plantes-descoberta-3-6","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/general\/experiment-amb-pinyes-les-plantes-descoberta-3-6\/","title":{"rendered":"EXPERIMENT AMB PINYES. LES PLANTES. DESCOBERTA 3-6."},"content":{"rendered":"<p>Us volem presentar l\u2019experiment que vam fer amb pinyes.<!--more--><\/p>\n<p>Primer les vam observar, tocar, olorar. Alguna pinya portava dins pinyons.<\/p>\n<p>Vam preparar el material per a fer l\u2019experiment. Primer els cossis, fent servir unes garrafes d\u2019aigua transparents tallades per la part de dalt. V\u00e0rem triar per fer l\u2019experiment pinyes que estaven obertes. I una gerra amb aigua. Amb tot el material vam iniciar la conversa amb la pregunta <em>Qu\u00e8 penseu que passar\u00e0 si posem aquestes pinyes amb aigua?<\/em><\/p>\n<p>Van formular les seves hip\u00f2tesis:<em> l\u2019aigua canviar\u00e0 de color, les pinyes es faran grans, suraran, els sortir\u00e0 una tija, es mullaran,&#8230;.<\/em><\/p>\n<p>I despr\u00e9s tocava comprovar-ho. Les pinyes van surar, es van mullar, l\u2019aigua va canviar de color i amb el que no compt\u00e0vem era que al cap d\u2019una estona AL MULLAR-SE, LES PINYES OBERTES ES VAN TANCAR! Creiem que d\u00b4aquesta manera quan plou els pinyons que estan a l\u2019interior de les pinyes queden protegits!<\/p>\n<p>Qu\u00e8 passar\u00e0 si les pinyes les traiem fora de l\u2019aigua? Les hem portat a la classe i ara haurem d\u2019esperar a que s\u00b4assequin. Pensem que les pinyes tornaran a obrir-se, per\u00f2 per veure-ho haurem d\u00b4esperar una miqueta.<\/p>\n<p><a href=\"https:\/\/photos.app.goo.gl\/Em8Rcw8ETMiNwRdJ6\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2914\" src=\"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-content\/uploads\/usu1367\/2019\/05\/2-1024x695.jpg\" alt=\"\" width=\"562\" height=\"381\" srcset=\"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-content\/uploads\/usu1367\/2019\/05\/2-1024x695.jpg 1024w, https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-content\/uploads\/usu1367\/2019\/05\/2-300x204.jpg 300w, https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-content\/uploads\/usu1367\/2019\/05\/2-768x522.jpg 768w\" sizes=\"auto, (max-width: 562px) 100vw, 562px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Us volem presentar l\u2019experiment que vam fer amb pinyes.<\/p>\n","protected":false},"author":1,"featured_media":2914,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65,1,103,104,4],"tags":[],"class_list":["post-2913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-descoberta-3-6","category-general","category-hem-fet-a-escola","category-infantil","category-portada"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-json\/wp\/v2\/posts\/2913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-json\/wp\/v2\/comments?post=2913"}],"version-history":[{"count":1,"href":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-json\/wp\/v2\/posts\/2913\/revisions"}],"predecessor-version":[{"id":2915,"href":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-json\/wp\/v2\/posts\/2913\/revisions\/2915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-json\/wp\/v2\/media\/2914"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-json\/wp\/v2\/media?parent=2913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-json\/wp\/v2\/categories?post=2913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-salvador-espriu-roda\/wp-json\/wp\/v2\/tags?post=2913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}