{"id":5194,"date":"2020-11-12T12:09:53","date_gmt":"2020-11-12T11:09:53","guid":{"rendered":"http:\/\/agora.xtec.cat\/ceip-celiaartiga\/?p=5194"},"modified":"2020-11-27T15:43:05","modified_gmt":"2020-11-27T14:43:05","slug":"resum-sessio-assemblea-9-11-2020","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/actes-assamblees\/resum-sessio-assemblea-9-11-2020\/","title":{"rendered":"Resum Sessi\u00f3 Assemblea 9\/11\/2020"},"content":{"rendered":"<p>El passat dilluns dia 9 de novembre de 2020 es va dur a terme el plenari de la junta de l&#8217;AMPA del centre, en el que es van tractar els temes que seguidament us adjuntem a mode de breu resum:<\/p>\n<p><a href=\"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-content\/uploads\/usu858\/2020\/11\/resum-ampa-web.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">ACTA JUNTA AMPA<\/a><\/p>\n<p>Aprofitem per recordar-vos que existeix\u00a0 la possibilitat de traslladar a la junta de l&#8217;AMPA\u00a0 qualsevol tem\u00e0tica que vulgueu que sigui tractada en aquestes sessions i que considereu que \u00e9s una q\u00fcesti\u00f3 que s\u2019hagi de posar en coneixement d\u2019aquesta associaci\u00f3.<br \/>\nLes fam\u00edlies que ho desitgin poden adre\u00e7ar-se a la junta al correu electr\u00f2nic <a href=\"mailto:consell.escolar@escolaceliaartiga.cat\" target=\"_blank\" rel=\"noopener noreferrer\">ampa@escolaceliaartiga.cat<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El passat dilluns dia 9 de novembre de 2020 es va dur a terme el plenari de la junta de l&#8217;AMPA del centre, en el que es van tractar els temes que seguidament us adjuntem a mode de breu resum:<br \/>\n<a href=\"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-content\/uploads\/usu858\/2020\/11\/resum-ampa-web.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">ACTA JUNTA&hellip;  <a href=\"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/actes-assamblees\/resum-sessio-assemblea-9-11-2020\/\" title=\"Read Resum Sessi\u00f3 Assemblea 9\/11\/2020\">Llegeix m\u00e9s\u00bb<\/a><\/p>\n","protected":false},"author":3,"featured_media":5175,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"footnotes":""},"categories":[102],"tags":[],"class_list":["post-5194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actes-assamblees"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-json\/wp\/v2\/posts\/5194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-json\/wp\/v2\/comments?post=5194"}],"version-history":[{"count":2,"href":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-json\/wp\/v2\/posts\/5194\/revisions"}],"predecessor-version":[{"id":5210,"href":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-json\/wp\/v2\/posts\/5194\/revisions\/5210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-json\/wp\/v2\/media\/5175"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-json\/wp\/v2\/media?parent=5194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-json\/wp\/v2\/categories?post=5194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-celiaartiga\/wp-json\/wp\/v2\/tags?post=5194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}