{"id":9065,"date":"2020-05-11T10:34:39","date_gmt":"2020-05-11T08:34:39","guid":{"rendered":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/?p=9065"},"modified":"2020-05-11T15:53:51","modified_gmt":"2020-05-11T13:53:51","slug":"a-les-vostres-mans","status":"publish","type":"post","link":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/general\/a-les-vostres-mans\/","title":{"rendered":"A LES VOSTRES MANS!"},"content":{"rendered":"<p>Quan tornem a l\u2019escola ser\u00e0 molt important que ens continuem rentant les mans sovint, tal com estem fent aquests dies a casa. Per aix\u00f2, els nens i nenes de quart han dissenyat un cartell amb un lema impactant i una imatge entenedora i atractiva que ens convidi a rentar-nos les mans. Aqu\u00ed us deixem uns quants!<\/p>\n\r\n\t<div class=\"slideshow_container slideshow_container_style-light\" style=\"height: 300px; \" data-slideshow-id=\"9047\" data-style-name=\"style-light\" data-style-version=\"2.3.1\" >\r\n\r\n\t\t\t\t\t<div class=\"slideshow_loading_icon\"><\/div>\r\n\t\t\r\n\t\t<div class=\"slideshow_content\" style=\"display: none;\">\r\n\r\n\t\t\t<div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.23.17_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.23.17_Easy-Resize.com\" width=\"1024\" height=\"578\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.23.17_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.22.56_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.22.56_Easy-Resize.com\" width=\"1024\" height=\"721\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.22.56_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.22.50_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.22.50_Easy-Resize.com\" width=\"1024\" height=\"688\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.22.50_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.05.57_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.05.57_Easy-Resize.com\" width=\"1024\" height=\"756\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.05.57_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.05.46_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.05.46_Easy-Resize.com\" width=\"1024\" height=\"688\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.05.46_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.05.38_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.05.38_Easy-Resize.com\" width=\"1024\" height=\"839\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.05.38_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.05.28_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.05.28_Easy-Resize.com\" width=\"1024\" height=\"764\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.05.28_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.05.19_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.05.19_Easy-Resize.com\" width=\"668\" height=\"1024\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.05.19_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.05.09_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.05.09_Easy-Resize.com\" width=\"1024\" height=\"707\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.05.09_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.05.00_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.05.00_Easy-Resize.com\" width=\"723\" height=\"1024\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.05.00_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.04.46_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.04.46_Easy-Resize.com\" width=\"1024\" height=\"762\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.04.46_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.04.36_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.04.36_Easy-Resize.com\" width=\"1024\" height=\"858\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.04.36_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.04.20_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.04.20_Easy-Resize.com\" width=\"1024\" height=\"570\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.04.20_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.03.57_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.03.57_Easy-Resize.com\" width=\"769\" height=\"1024\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.03.57_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div><div class=\"slideshow_view\">\r\n\t\t\t\t<div class=\"slideshow_slide slideshow_slide_image\">\r\n\t\t\t\t\t\t\t\t\t\t\t<img src=\"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-content\/uploads\/usu261\/2020\/05\/Captura-de-pantalla-2020-05-11-a-las-10.03.28_Easy-Resize.com_.jpg\" alt=\"Captura de pantalla 2020-05-11 a las 10.03.28_Easy-Resize.com\" width=\"1024\" height=\"853\" \/>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"slideshow_description_box slideshow_transparent\">\r\n\t\t\t\t\t\t<div class=\"slideshow_title\">Captura de pantalla 2020-05-11 a las 10.03.28_Easy-Resize.com<\/div>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t<div style=\"clear: both;\"><\/div><\/div>\r\n\t\t<\/div>\r\n\r\n\t\t<div class=\"slideshow_controlPanel slideshow_transparent\" style=\"display: none;\"><ul><li class=\"slideshow_togglePlay\" data-play-text=\"Visualitza\" data-pause-text=\"Pausa\"><\/li><\/ul><\/div>\r\n\r\n\t\t<div class=\"slideshow_button slideshow_previous slideshow_transparent\" role=\"button\" data-previous-text=\"Anterior\" style=\"display: none;\"><\/div>\r\n\t\t<div class=\"slideshow_button slideshow_next slideshow_transparent\" role=\"button\" data-next-text=\"Seg\u00fcent\" style=\"display: none;\"><\/div>\r\n\r\n\t\t<div class=\"slideshow_pagination\" style=\"display: none;\" data-go-to-text=\"V\u00e9s a la diapositiva\"><div class=\"slideshow_pagination_center\"><\/div><\/div>\r\n\r\n\t\t<!-- WordPress Slideshow Version 2.3.1 -->\r\n\r\n\t\t\t<\/div>\r\n\r\n\n","protected":false},"excerpt":{"rendered":"<p>Quan tornem a l\u2019escola ser\u00e0 molt important que ens continuem rentant les mans sovint, tal com estem fent aquests dies a casa. Per aix\u00f2, els nens i nenes de quart han dissenyat un cartell amb un lema impactant i una imatge entenedora i atractiva que ens convidi a rentar-nos les mans. Aqu\u00ed us deixem uns [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":9062,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[13,1,52,4,5],"tags":[],"class_list":["post-9065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-4t","category-general","category-grans","category-portada","category-primaria"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-json\/wp\/v2\/posts\/9065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-json\/wp\/v2\/comments?post=9065"}],"version-history":[{"count":2,"href":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-json\/wp\/v2\/posts\/9065\/revisions"}],"predecessor-version":[{"id":9086,"href":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-json\/wp\/v2\/posts\/9065\/revisions\/9086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-json\/wp\/v2\/media\/9062"}],"wp:attachment":[{"href":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-json\/wp\/v2\/media?parent=9065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-json\/wp\/v2\/categories?post=9065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agora.xtec.cat\/ceip-canpalmer\/wp-json\/wp\/v2\/tags?post=9065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}